{"id":24,"date":"2020-06-15T19:21:45","date_gmt":"2020-06-15T19:21:45","guid":{"rendered":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/product\/import-placeholder-for-75\/"},"modified":"2020-06-15T19:22:01","modified_gmt":"2020-06-15T19:22:01","slug":"single","status":"publish","type":"product","link":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/product\/single\/","title":{"rendered":"Single"},"content":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Vestibulum sagittis orci ac odio dictum tincidunt. Donec ut metus leo. Class aptent taciti sociosqu ad litora torquent per conubia nostra, per inceptos himenaeos. Sed luctus, dui eu sagittis sodales, nulla nibh sagittis augue, vel porttitor diam enim non metus. Vestibulum aliquam augue neque. Phasellus tincidunt odio eget ullamcorper efficitur. Cras placerat ut turpis pellentesque vulputate. Nam sed consequat tortor. Curabitur finibus sapien dolor. Ut eleifend tellus nec erat pulvinar dignissim. Nam non arcu purus. Vivamus et massa massa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is a simple, virtual product.<\/p>\n","protected":false},"featured_media":53,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-24","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-music","8":"first","9":"instock","10":"sale","11":"downloadable","12":"virtual","13":"taxable","14":"purchasable","15":"product-type-simple","16":"entry","17":"content-bg","18":"loop-entry"},"_links":{"self":[{"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/product\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/comments?post=24"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/media\/53"}],"wp:attachment":[{"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/product_brand?post=24"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/product_cat?post=24"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/demo.devdiggers.com\/progressive-web-app-for-wordpress\/wp-json\/wp\/v2\/product_tag?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}